{"id":96922,"date":"2024-06-19T17:41:31","date_gmt":"2024-06-19T17:41:31","guid":{"rendered":"https:\/\/www.switcho.it\/blog\/?p=96922"},"modified":"2024-06-19T17:41:32","modified_gmt":"2024-06-19T17:41:32","slug":"arera-medreg-nuove-strategie-energetiche","status":"publish","type":"post","link":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/","title":{"rendered":"ARERA e le Authority del Mediterraneo si incontrano per definire nuove strategie energetiche"},"content":{"rendered":"\n<p>L\u2019<strong>incontro tra ARERA e MEDREG<\/strong> ha avuto luogo nel sito archeologico di Selinunte (Trapani) per discutere e definire strategie efficaci per promuovere gli investimenti nelle interconnessioni transfrontaliere e nelle infrastrutture energetiche. In pillole:<\/p>\n\n\n\n<ul class=\"emoji_bullets emoji_check_mark wp-block-list\">\n<li>All\u2019incontro hanno partecipato l\u2019<strong>Autorit\u00e0 di Regolazione per Reti Energia e Ambiente<\/strong>, i membri di <strong>MEDREG<\/strong>, le <strong>aziende leader nel settore<\/strong> e i <strong>rappresentanti istituzionali<\/strong> di tutta la regione mediterranea.<\/li>\n\n\n\n<li>L\u2019obiettivo dell\u2019incontro \u00e8 stato rafforzare le <strong>infrastrutture interconnesse<\/strong> e promuovere l&#8217;<strong>integrazione dei sistemi energetici<\/strong> nella regione euro-mediterranea, al fine di trovare soluzioni innovative per un futuro energetico sostenibile e decarbonizzato, tenendo conto dei cambiamenti nel panorama energetico.<\/li>\n\n\n\n<li>Il Ministro dell\u2019Ambiente, <strong>Gilberto Pichetto Fratin<\/strong>, ha evidenziato il ruolo centrale dell\u2019Italia come ponte energetico centrale nel Mediterraneo, ponendo l\u2019obiettivo di una cooperazione energetica tra i Paesi della regione e la realizzazione di una transizione energetica equa e sostenibile.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.18.0&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.19.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/03\/banner-luce-gas-top-desktop-new.png&#8221; alt=&#8221;Risparmia sulle bollette con Switcho&#8221; title_text=&#8221;risparmia sulle bollette con switcho&#8221; url=&#8221;http:\/\/www.switcho.it\/servizi\/intro\/luce-gas?ref=cta-energy-top&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; src_tablet=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-top-mobile.png&#8221; src_phone=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-top-mobile.png&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Indice<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#rafforzare-collaborazione\">ARERA e MEDREG per rafforzare la collaborazione tra i paesi del Mediterraneo<\/a><\/li>\n\n\n\n<li><a href=\"#fratin-strategia-italiana\">Incontro ARERA \u2013 MEDREG: Gilberto Fratin presenta la Strategia energetica italiana<\/a><\/li>\n\n\n\n<li><a href=\"#medreg-anticipare-cambiamenti\">Il Presidente di MEDREG: anticipare i cambiamenti futuri nel panorama energetico<\/a><\/li>\n\n\n\n<li><a href=\"#confronto-trend-energetici\">Il confronto tra Terna, Snam, Edf ed Eni sui trend energetici della regione<\/a><\/li>\n\n\n\n<li><a href=\"#cooperazione-priorita-ue\">La cooperazione energetica nel Mediterraneo come priorit\u00e0 strategica per l\u2019UE<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rafforzare-collaborazione\"><strong>ARERA e MEDREG per rafforzare la collaborazione tra i paesi del Mediterraneo<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si sono incontrati nel <strong>sito archeologico di Selinunte<\/strong> ARERA e MEDREG per un confronto dal quale far emergere nuove strategie vincenti, attrarre investimenti infrastrutturali e sfruttare appieno il potenziale delle energie rinnovabili della regione mediterranea.&nbsp;<\/p>\n\n\n\n<p>Diversi i partecipanti all\u2019incontro, tra rappresentanti istituzionali e aziende del settore, in particolare:&nbsp;<\/p>\n\n\n\n<ul class=\"emoji_bullets emoji_right_arrow wp-block-list\">\n<li><strong>ARERA<\/strong>, l\u2019Autorit\u00e0 che svolge l\u2019attivit\u00e0 di regolazione e controllo sui settori dell\u2019energia elettrica, del gas naturale e dei servizi idrici nel nostro Paese;<\/li>\n\n\n\n<li><strong>I membri di MEDREG<\/strong>, l\u2019associazione dei regolatori del Mediterraneo \u2013 il cui Vicepresidente permanente \u00e8 Stefano Besseghini, anche presidente di ARERA \u2013 che raccoglie 28 regolatori dell\u2019energia di 23 Paesi (Albania, Algeria, Bosnia-Erzegovina, Croazia, Cipro, Egitto, Francia, Grecia, Israele, Italia, Giordania, Libano, Libia, Malta, Montenegro, Marocco, Macedonia del Nord, Autorit\u00e0 Palestinese, Portogallo, Slovenia, Spagna, Tunisia e Turchia);<\/li>\n\n\n\n<li><strong>Il<\/strong> <strong>Ministro dell\u2019Ambiente e della sicurezza energetica<\/strong>, Gilberto Pichetto Fratin;<\/li>\n\n\n\n<li>I massimi rappresentanti delle aziende <strong>Terna, Snam, Edf ed Eni<\/strong> e l\u2019Ufficio per l\u2019elettricit\u00e0 e l\u2019acqua potabile del Marocco.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"has-background\" style=\"background-color:#f7f8fa\">\ud83c\udfaf L\u2019obiettivo dell\u2019incontro \u00e8 stato il confronto su una <strong>regolamentazione coerente a livello regionale<\/strong>, puntando su investimenti infrastrutturali, sul commercio transfrontaliero e sull\u2019integrazione delle energie rinnovabili affinch\u00e9 la regione mediterranea possa diventare un <strong>polo energetico sostenibile<\/strong> in grado di fornire energia sicura, affidabile e a prezzi accessibili ai suoi cittadini.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fratin-strategia-italiana\"><strong>Incontro ARERA \u2013 MEDREG: Gilberto Fratin presenta la Strategia energetica italiana<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Presente all\u2019incontro anche il nostro <strong>Ministro dell\u2019Ambiente e della sicurezza energetica, Gilberto Pichetto Fratin<\/strong>, che ha presentato la Strategia energetica italiana.&nbsp;<\/p>\n\n\n\n<p>Il Ministro ha posto l\u2019accento sulle potenzialit\u00e0 del nostro Paese per affermarsi come <strong>polo energetico tra il Nord e il Sud, l\u2019Est e Ovest nel bacino mediterraneo<\/strong>, riconoscendo il ruolo centrale del Mar Mediterraneo nello scenario energetico globale.&nbsp;<\/p>\n\n\n\n<p>Fondamentale \u00e8 il ruolo dei Regolatori, in questo senso. Come affermato dal Ministro Fratin:<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201cIn un contesto caratterizzato da <\/em><strong><em>nuove dinamiche internazionali<\/em><\/strong><em> intrecciate con la sicurezza e la sostenibilit\u00e0 energetica, il ruolo dei Regolatori \u00e8 cruciale. L&#8217;obiettivo comune \u00e8 promuovere la <\/em><strong><em>cooperazione energetica tra i Paesi del Mediterraneo<\/em><\/strong><em> e realizzare una <\/em><strong><em>transizione energetica socialmente equa<\/em><\/strong><em> che non lasci indietro nessuno.\u201d<\/em><\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"medreg-anticipare-cambiamenti\"><strong>Il Presidente di MEDREG: anticipare i cambiamenti futuri nel panorama energetico<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il panorama energetico \u00e8 in rapida evoluzione. Lo ricorda il <strong>Presidente di MEDREG e di ANRE<\/strong>, l&#8217;Autorit\u00e0 marocchina di Regolazione dell&#8217;energia elettrica, <strong>Abdellatif Bardach<\/strong>, secondo il quale il dialogo energetico regionale \u00e8 chiamato tanto ad affrontare le sfide attuali, quanto ad anticipare i futuri cambiamenti del panorama energetico.&nbsp;<\/p>\n\n\n\n<p>Obiettivi, questi, che possono essere raggiunti grazie al dialogo tra i paesi del Mediterraneo:\u00a0<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&nbsp;<em>\u201cLe nostre discussioni di oggi si sono concentrate sul <\/em><strong><em>rafforzamento delle nostre infrastrutture<\/em><\/strong><em> interconnesse e sulla promozione di una maggiore integrazione dei sistemi energetici nell&#8217;intera regione euro-mediterranea. Il nostro obiettivo principale \u00e8 scoprire <\/em><strong><em>soluzioni innovative<\/em><\/strong><em> che non solo ci guidino verso un futuro energetico sostenibile e decarbonizzato, ma ci consentano anche di <\/em><strong><em>adattarci al panorama energetico in rapida evoluzione<\/em><\/strong>.&#8221;&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p>Anche <strong>Stefano Besseghini<\/strong>, il presidente di ARERA, ha sottolineato l\u2019importanza di una collaborazione tra i Regolatori dell\u2019energia nell\u2019area mediterranea, una cooperazione necessaria per:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sviluppare un <strong>quadro normativo uniforme<\/strong> a livello regionale;<\/li>\n\n\n\n<li>Attrarre <strong>investimenti infrastrutturali<\/strong>;<\/li>\n\n\n\n<li>Massimizzare il potenziale delle energie rinnovabili e del GNL nel Mediterraneo;<\/li>\n\n\n\n<li><strong>Decarbonizzare<\/strong> il settore energetico.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"confronto-trend-energetici\"><strong>Il confronto tra Terna, Snam, Edf ed Eni sui trend energetici della regione<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Durante l\u2019incontro, i Presidenti delle autorit\u00e0 di regolazione dell&#8217;energia e i dirigenti delle principali aziende energetiche, come <strong>Terna, Snam, Edf, Eni e l&#8217;Ufficio per l&#8217;elettricit\u00e0 e l&#8217;acqua potabile del Marocco<\/strong>, hanno avviato un confronto per esaminare modelli di business innovativi, meccanismi di finanziamento e strategie per promuovere la diffusione delle energie rinnovabili nelle aree isolate.<\/p>\n\n\n\n<p>Autorit\u00e0 e aziende leader del settore hanno discusso delle <strong>tendenze pi\u00f9 recenti nel settore energetico<\/strong> della regione e dei progetti attuati per sviluppare ulteriormente il mercato energetico locale. Hanno anche esaminato le opportunit\u00e0 offerte dall&#8217;area in termini di produzione e commercio di energia, individuando sfide come <strong>infrastrutture obsolete o inadeguate, elevate necessit\u00e0 di investimento, ostacoli tecnici e politiche e normative divergenti.<\/strong><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cooperazione-priorita-ue\"><strong>La cooperazione energetica nel Mediterraneo come priorit\u00e0 strategica per l\u2019UE<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La cooperazione energetica nel Mediterraneo \u00e8 una <strong>priorit\u00e0 strategica per l\u2019Unione Europea<\/strong>. Lo ha affermato <strong>Stefano Grassi<\/strong>, Capo di gabinetto del Commissario europeo per l\u2019energia.&nbsp;<\/p>\n\n\n\n<p>Questo \u00e8 ancor pi\u00f9 essenziale in un momento storico in cui l\u2019Europa sta <strong>riorganizzando le vie di fornitura e la rete di partner<\/strong> per <a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/gas-russo-italia-2024-2025\/\">ridurre progressivamente le importazioni di combustibili fossili dalla Russia<\/a>. Secondo Grassi:\u00a0<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201cIl Mediterraneo pu\u00f2 diventare la <\/em><strong><em>futura centrale dell&#8217;economia verde europea<\/em><\/strong><em>, basata sulle esportazioni di energia rinnovabile, idrogeno e gas rinnovabili. L&#8217;allineamento dei quadri normativi tra i paesi delle due sponde, la promozione della collaborazione nella pianificazione e nel finanziamento delle infrastrutture e la creazione di fiducia reciproca sono ingredienti chiave per una migliore cooperazione regionale.\u201d<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Per Grassi, l\u2019azione dei regolatori \u00e8 essenziale per aprire il dialogo e prevedere nuove <strong>azioni vantaggiose per il Mediterraneo e per l\u2019UE<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Si tratta dei primi passi verso un mercato energetico mediterraneo pi\u00f9 resiliente e integrato: tutto parte dalla <strong>cooperazione regionale<\/strong>, da nuovi investimenti in <strong>infrastrutture moderne<\/strong>, dall\u2019adozione di normative convergenti e dalla promozione di pratiche energetiche sostenibili a livello regionale.\u00a0Obiettivi, questi, che <strong>MEDREG porta avanti costantemente<\/strong>, anche tramite incontri come quello con ARERA, istituzioni e aziende leader del settore, come quello avvenuto pochi giorni fa a Selinunte.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_toggle title=&#8221;Fonti&#8221; open_toggle_background_color=&#8221;#F7F8FA&#8221; closed_toggle_text_color=&#8221;#2D3748&#8243; closed_toggle_background_color=&#8221;#f7f8fa&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;||||||||&#8221; title_font_size=&#8221;18px&#8221; title_line_height=&#8221;1.7em&#8221; closed_title_font=&#8221;||||||||&#8221; closed_title_font_size=&#8221;18px&#8221; body_font=&#8221;||||||||&#8221; hover_enabled=&#8221;0&#8243; body_font_size_tablet=&#8221;16px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<span>Presidenti dei Regolatori dell\u2019energia, rappresentanti istituzionali del Mediterraneo e aziende del settore insieme per rafforzare la collaborazione tra i Paesi dell\u2019area e lo scambio di best practice | ARERA\n<\/span>\n<br><span><a href=\"https:\/\/www.arera.it\/comunicati-stampa\/dettaglio\/presidenti-dei-regolatori-dellenergia-rappresentanti-istituzionali-del-mediterraneo-e-aziende-del-settore-insieme-per-rafforzare-la-collaborazione-tra-i-paesi-dellarea-e-lo-scambio-di-best-practice\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.arera.it\/comunicati-stampa\/dettaglio\/presidenti-dei-regolatori-dellenergia-rappresentanti-istituzionali-del-mediterraneo-e-aziende-del-settore-insieme-per-rafforzare-la-collaborazione-tra-i-paesi-dellarea-e-lo-scambio-di-best-practice<\/a><\/span>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.<\/p>\n","protected":false},"author":23,"featured_media":96925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[307],"tags":[403],"class_list":["post-96922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercato-energia","tag-news-luce-gas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARERA e MEDREG insieme per definire nuove strategie energetiche - Switcho<\/title>\n<meta name=\"description\" content=\"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARERA e MEDREG insieme per definire nuove strategie energetiche\" \/>\n<meta property=\"og:description\" content=\"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Switcho\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T17:41:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T17:41:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Tricarico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Tricarico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/\"},\"author\":{\"name\":\"Marco Tricarico\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/person\\\/4a59c480dfc019823d29714bd644a488\"},\"headline\":\"ARERA e le Authority del Mediterraneo si incontrano per definire nuove strategie energetiche\",\"datePublished\":\"2024-06-19T17:41:31+00:00\",\"dateModified\":\"2024-06-19T17:41:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/\"},\"wordCount\":1311,\"publisher\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/arera-medreg.jpg\",\"keywords\":[\"news luce e gas\"],\"articleSection\":[\"Mercato Energetico\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/\",\"name\":\"ARERA e MEDREG insieme per definire nuove strategie energetiche - Switcho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/arera-medreg.jpg\",\"datePublished\":\"2024-06-19T17:41:31+00:00\",\"dateModified\":\"2024-06-19T17:41:32+00:00\",\"description\":\"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/arera-medreg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/arera-medreg.jpg\",\"width\":1200,\"height\":800,\"caption\":\"ARERA e le Authority del Mediterraneo si incontrano per una pi\u00f9 stretta collaborazione\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/arera-medreg-nuove-strategie-energetiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luce e Gas\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercato Energetico\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/mercato-energia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ARERA e le Authority del Mediterraneo si incontrano per definire nuove strategie energetiche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\",\"name\":\"Switcho\",\"description\":\"Il blog semplice, per davvero.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\",\"name\":\"Switcho\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Switcho-Logotype-Green.png\",\"contentUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Switcho-Logotype-Green.png\",\"width\":1507,\"height\":597,\"caption\":\"Switcho\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/person\\\/4a59c480dfc019823d29714bd644a488\",\"name\":\"Marco Tricarico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g\",\"caption\":\"Marco Tricarico\"},\"description\":\"CEO e co-fondatore di Switcho, appassionato di startup e mondo digitale ed esperto di finanza aziendale e consulenza strategica, nel 2019 Marco ha deciso di lanciare un servizio innovativo che offrisse una soluzione di risparmio pratica e realmente imparziale sulle bollette di famiglie e aziende. Dalla nascita di Switcho, Marco partecipa a svariati eventi e rilascia interviste sui temi delle spese domestiche e del settore energetico, parlando delle ultime tendenze nei costi di gas ed elettricit\u00e0 e delle migliori opportunit\u00e0 per tutelarsi dai rincari. Leggi tutti i suoi articoli e seguilo su LinkedIn.\",\"sameAs\":[\"https:\\\/\\\/blog.switcho.net\"],\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/author\\\/marco-tricarico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARERA e MEDREG insieme per definire nuove strategie energetiche - Switcho","description":"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/","og_locale":"it_IT","og_type":"article","og_title":"ARERA e MEDREG insieme per definire nuove strategie energetiche","og_description":"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.","og_url":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/","og_site_name":"Switcho","article_published_time":"2024-06-19T17:41:31+00:00","article_modified_time":"2024-06-19T17:41:32+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg","type":"image\/jpeg"}],"author":"Marco Tricarico","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Marco Tricarico","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#article","isPartOf":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/"},"author":{"name":"Marco Tricarico","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/person\/4a59c480dfc019823d29714bd644a488"},"headline":"ARERA e le Authority del Mediterraneo si incontrano per definire nuove strategie energetiche","datePublished":"2024-06-19T17:41:31+00:00","dateModified":"2024-06-19T17:41:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/"},"wordCount":1311,"publisher":{"@id":"https:\/\/www.switcho.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg","keywords":["news luce e gas"],"articleSection":["Mercato Energetico"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/","url":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/","name":"ARERA e MEDREG insieme per definire nuove strategie energetiche - Switcho","isPartOf":{"@id":"https:\/\/www.switcho.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#primaryimage"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg","datePublished":"2024-06-19T17:41:31+00:00","dateModified":"2024-06-19T17:41:32+00:00","description":"ARERA e MEDREG si confrontano su strategie e investimenti per sfruttare il ruolo centrale del Mediterraneo nel panorama energetico.","breadcrumb":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#primaryimage","url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg","contentUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/06\/arera-medreg.jpg","width":1200,"height":800,"caption":"ARERA e le Authority del Mediterraneo si incontrano per una pi\u00f9 stretta collaborazione"},{"@type":"BreadcrumbList","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/arera-medreg-nuove-strategie-energetiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.switcho.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Luce e Gas","item":"https:\/\/www.switcho.it\/blog\/luce-gas\/"},{"@type":"ListItem","position":3,"name":"Mercato Energetico","item":"https:\/\/www.switcho.it\/blog\/luce-gas\/mercato-energia\/"},{"@type":"ListItem","position":4,"name":"ARERA e le Authority del Mediterraneo si incontrano per definire nuove strategie energetiche"}]},{"@type":"WebSite","@id":"https:\/\/www.switcho.it\/blog\/#website","url":"https:\/\/www.switcho.it\/blog\/","name":"Switcho","description":"Il blog semplice, per davvero.","publisher":{"@id":"https:\/\/www.switcho.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.switcho.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.switcho.it\/blog\/#organization","name":"Switcho","url":"https:\/\/www.switcho.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2021\/03\/Switcho-Logotype-Green.png","contentUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2021\/03\/Switcho-Logotype-Green.png","width":1507,"height":597,"caption":"Switcho"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/person\/4a59c480dfc019823d29714bd644a488","name":"Marco Tricarico","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a8a5d0321dce5e64611bac7a181edfc33d850ac6202cd0adaab2ece13fbcd6a?s=96&d=mm&r=g","caption":"Marco Tricarico"},"description":"CEO e co-fondatore di Switcho, appassionato di startup e mondo digitale ed esperto di finanza aziendale e consulenza strategica, nel 2019 Marco ha deciso di lanciare un servizio innovativo che offrisse una soluzione di risparmio pratica e realmente imparziale sulle bollette di famiglie e aziende. Dalla nascita di Switcho, Marco partecipa a svariati eventi e rilascia interviste sui temi delle spese domestiche e del settore energetico, parlando delle ultime tendenze nei costi di gas ed elettricit\u00e0 e delle migliori opportunit\u00e0 per tutelarsi dai rincari. Leggi tutti i suoi articoli e seguilo su LinkedIn.","sameAs":["https:\/\/blog.switcho.net"],"url":"https:\/\/www.switcho.it\/blog\/author\/marco-tricarico\/"}]}},"modified_by":"Gabriele Toninelli","_links":{"self":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/96922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/comments?post=96922"}],"version-history":[{"count":4,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/96922\/revisions"}],"predecessor-version":[{"id":96961,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/96922\/revisions\/96961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/media\/96925"}],"wp:attachment":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/media?parent=96922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/categories?post=96922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/tags?post=96922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}