{"id":152273,"date":"2026-02-20T11:48:09","date_gmt":"2026-02-20T11:48:09","guid":{"rendered":"https:\/\/www.switcho.it\/blog\/?p=152273"},"modified":"2026-02-20T11:48:10","modified_gmt":"2026-02-20T11:48:10","slug":"numero-verde-contatti-octopus","status":"publish","type":"post","link":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/","title":{"rendered":"Numero verde Octopus e contatti del servizio clienti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se hai bisogno di supporto, puoi contattare il <strong>servizio clienti Octopus<\/strong>. Octopus non ha un vero e proprio <strong>numero verde<\/strong>, ma ci sono diversi contatti che puoi utilizzare per ricevere assistenza:&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>CANALE<\/strong><\/th><th><strong>CANALE<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Numero<\/strong> (clienti domestici e business)<\/td><td>02 38582776<\/td><\/tr><tr><td><strong>Whatsapp<\/strong><\/td><td>02 38582776<\/td><\/tr><tr><td><strong>Email<\/strong><\/td><td><a href=\"mailto:ciao@octopusenergy.it\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">ciao@octopusenergy.it<\/a><\/td><\/tr><tr><td><strong>Area Clienti<\/strong><\/td><td><a href=\"https:\/\/octopusenergy.it\/login?_gl=1*mfy6zw*_up*MQ..*_gs*MQ..&amp;gclid=CjwKCAiAwNDMBhBfEiwAd7ti1AZHKcvpZPdA8cpYfXEEz6cir3IM-6ebWxcDfw40RUEmQRamXp0AuRoC6ewQAvD_BwE&amp;gbraid=0AAAAAohVjut48F75Z9T2f_DUtJS1GRskX\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Login<\/a><\/td><\/tr><tr><td><strong>App<\/strong><\/td><td>App Octopus Energy<\/td><\/tr><tr><td><strong>Indirizzo sede legale<\/strong><\/td><td>Via dei Gorghi 9, 63100 Ascoli Piceno (AP)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"article-cta wp-block-paragraph\">Sei ancora alla ricerca dell\u2019offerta pi\u00f9 in linea con le tue esigenze? <a href=\"https:\/\/www.switcho.it\/servizi\/intro\/luce-gas\"><strong>Noi di Switcho<\/strong><\/a> ti aiutiamo a individuare le <a href=\"https:\/\/www.switcho.it\/risorse\/luce-gas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>offerte luce e gas<\/strong><\/a> pi\u00f9 convenienti e ci occupiamo anche di tutta la burocrazia legata al cambio fornitore. Il tutto, <strong>in pochi clic e gratis<\/strong>.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.18.0&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.19.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2024\/03\/banner-luce-gas-top-desktop-new.png&#8221; alt=&#8221;Risparmia sulle bollette con Switcho&#8221; title_text=&#8221;risparmia sulle bollette con switcho&#8221; url=&#8221;http:\/\/www.switcho.it\/servizi\/intro\/luce-gas?ref=cta-energy-top&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; src_tablet=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-top-mobile.png&#8221; src_phone=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-top-mobile.png&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Indice<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#numero-verde\" type=\"internal\" id=\"#numero-verde\">Numero verde Octopus Energy per clienti domestici e business<\/a><\/li>\n\n\n\n<li><a href=\"#email-wz\" type=\"internal\" id=\"#email-wz\">Octopus contatti email e Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"#online-app\" type=\"internal\" id=\"#online-app\">Servizio clienti Octopus online: dall\u2019Area clienti all\u2019app<\/a><\/li>\n\n\n\n<li><a href=\"#reclami\" type=\"internal\" id=\"#reclami\">Numero di telefono Octopus e altri canali per inviare un reclamo<\/a><\/li>\n\n\n\n<li><a href=\"#interruzioni\" type=\"internal\" id=\"#interruzioni\">Contatti Octopus in caso di interruzioni di fornitura<\/a><\/li>\n\n\n\n<li><a href=\"#valutazione\" type=\"internal\" id=\"#valutazione\">Come viene valutato il servizio clienti Octopus<\/a><\/li>\n\n\n\n<li><a href=\"#switch\" type=\"internal\" id=\"#switch\">Come passare a Octopus Energy<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"numero-verde\"><strong>Numero verde Octopus Energy per clienti domestici e business<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Octopus non ha un vero e proprio <strong>numero verde<\/strong>. Mette per\u00f2 a disposizione un numero di telefono per mettersi in contatto con il suo pluripremiato servizio clienti.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>I clienti domestici e business possono <\/em><strong><em>contattare Octopus al 02 38582776<\/em><\/strong><em>, attivo dal luned\u00ec al venerd\u00ec, <\/em><strong><em>dalle 9.00 alle 17.00<\/em><\/strong><em>.&nbsp;<\/em><\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#f7f8fa\">\ud83d\udca1 Se chiami dall\u2019estero, puoi utilizzare lo stesso numero, <strong>preceduto dal prefisso +39<\/strong>.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi chiamare questo numero per richiedere assistenza su:<\/p>\n\n\n\n<ul class=\"wp-block-list emoji_bullets emoji_right_arrow\">\n<li>Bollette;<\/li>\n\n\n\n<li>Attivazioni;<\/li>\n\n\n\n<li>Contratto;<\/li>\n\n\n\n<li>Pratiche amministrative;<\/li>\n\n\n\n<li>Molto altro.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Prima di chiamare, ti consigliamo di avere a portata di mano alcune informazioni che possono facilitare la risoluzione dei problemi, per esempio il tuo <a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/codice-cliente\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>codice cliente<\/strong><\/a> e i codici <a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/codice-pod\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>POD<\/strong><\/a> \u2013 per l\u2019energia elettrica \u2013 e <a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/codice-pdr\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>PDR<\/strong><\/a> \u2013 per il gas.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"email-wz\"><strong>Octopus contatti email e Whatsapp<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre ad avere la possibilit\u00e0 di contattare Octopus tramite telefono, puoi metterti in contatto con l\u2019assistenza clienti anche tramite:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Email<\/strong>, scrivendo all\u2019indirizzo <strong><a href=\"mailto:ciao@octopusenergy.it\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">ciao@octopusenergy.it<\/a><\/strong> attivo dal luned\u00ec al venerd\u00ec, <strong>dalle 9.00 alle 17.00<\/strong>;<\/li>\n\n\n\n<li><strong>Whatsapp<\/strong> al numero <strong>02 38582776<\/strong>.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"online-app\"><strong>Servizio clienti Octopus online: dall\u2019Area clienti all\u2019app<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Come ormai la maggior parte degli operatori, anche Octopus mette a disposizione dei suoi clienti un\u2019<strong>Area personale<\/strong> dalla quale puoi effettuare una serie di operazioni in autonomia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per accedere all\u2019Area clienti Octopus, ti basta raggiungere il sito ufficiale e cliccare sulla voce <strong>Accedi<\/strong> in alto a destra. Dovrai poi inserire le tue credenziali per completare l\u2019accesso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dall\u2019Area clienti puoi:<\/p>\n\n\n\n<ul class=\"wp-block-list emoji_bullets emoji_right_arrow\">\n<li>Ricevere aggiornamenti, iniziative e comunicazioni da Octopus;<\/li>\n\n\n\n<li>Inviare l\u2019<a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/lettura-contatore-gas\/\" type=\"link\" id=\"https:\/\/www.switcho.it\/blog\/luce-gas\/lettura-contatore-gas\/\" target=\"_blank\" rel=\"noreferrer noopener\">autolettura del contatore del gas<\/a>;<\/li>\n\n\n\n<li>Consultare lo storico delle bollette e dei pagamenti.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre all\u2019Area clienti sul sito, per consultare i dati della fornitura, monitorare i consumi e tenere sott\u2019occhio i pagamenti, puoi utilizzare anche l\u2019<strong>app Octopus Energy.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi <strong>scaricarla dal <\/strong><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=energy.octopus.octopusenergy.android&amp;hl=en\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Play Store<\/strong><\/a>, se hai uno smartphone con sistema operativo Android, <strong>oppure da <\/strong><a href=\"https:\/\/apps.apple.com\/it\/app\/octopus-energy\/id1093452209\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>App Store<\/strong><\/a>, se hai un iPhone.&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"reclami\"><strong>Numero di telefono Octopus e altri canali per inviare un reclamo<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Quando riscontri un problema con i servizi Octopus, la prima cosa da fare \u00e8 contattare l\u2019operatore tramite:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Telefono al <strong>02 38582776<\/strong> (anche tramite Whatsapp);<\/li>\n\n\n\n<li>Email all\u2019indirizzo <strong>ciao@octopusenergy.it<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Qualora l\u2019assistenza clienti non sia stata in grado di risolvere il problema, puoi aprire un <strong>reclamo formale<\/strong>, anche compilando in autonomia il <a href=\"https:\/\/a.storyblok.com\/f\/146593\/x\/5d0d975df8\/oeitalia_modulo-reclami_250121.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">modulo<\/a> apposito.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"interruzioni\"><strong>Contatti Octopus in caso di interruzioni di fornitura<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In caso di <strong>guasti, malfunzionamenti o anomalie al contatore<\/strong>, \u00e8 importante sapere che l\u2019intervento tecnico viene gestito esclusivamente dal <a href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/distributore-energia-elettrica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>distributore di zona<\/strong><\/a>, cio\u00e8 l\u2019ente che opera sulla rete elettrica e sui contatori nella tua area. Questo significa che <strong>Octopus Energy non pu\u00f2 intervenire direttamente<\/strong> per risolvere questo tipo di problemi.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Il numero di emergenza del distributore \u00e8 sempre indicato nella tua area personale e su ogni bolletta e il <strong>servizio \u00e8 gratuito ed \u00e8 attivo 24 ore su 24, 7 giorni su 7.<\/strong>&nbsp;<\/em><\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Prima di contattarlo, per\u00f2, il consiglio \u00e8 fare qualche <strong>semplice verifica<\/strong>, per esempio controlla se hai acceso troppi elettrodomestici contemporaneamente, se sei in regola con i pagamenti o se il problema riguarda solo la tua abitazione o anche il quartiere.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udca1 In alcuni casi, potrebbe trattarsi di un\u2019<strong>interruzione programmata<\/strong>. Puoi verificarlo consultando il sito del distributore.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"valutazione\"><strong>Come viene valutato il servizio clienti Octopus<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tieni presente che il servizio clienti Octopus \u00e8 valutato <strong>5 stelle da oltre il 95% degli utenti<\/strong>. In pi\u00f9, \u00e8 stato riconosciuto come il <a href=\"https:\/\/www.corriere.it\/economia\/italy-best-customer-service\/2024\/index.shtml?servizi\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>miglior servizio clienti 2024\/25 e 2025\/2026<\/strong> dal Corriere della Sera<\/a> per il servizio di energia elettrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le buone valutazioni derivano probabilmente da due fattori:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list emoji_bullets emoji_right_arrow\">\n<li>La <strong>rapidit\u00e0<\/strong> con cui gli operatori rispondono al telefono e risolvono le richieste;<\/li>\n\n\n\n<li>Il fatto che il team sia composto da <strong>professionisti interni all\u2019azienda<\/strong>.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"switch\"><strong>Come passare a Octopus Energy<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se vuoi <strong>passare a Octopus puoi fare tutto online<\/strong>, registrandoti sul sito e fornendo alcune info come:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list emoji_bullets emoji_right_arrow\">\n<li>POD e PDR;<\/li>\n\n\n\n<li>Ultima bolletta;<\/li>\n\n\n\n<li>IBAN (se scegli l\u2019addebito diretto su conto corrente).&nbsp;<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"article-cta wp-block-paragraph\">In alternativa, ti aiutiamo <a href=\"https:\/\/www.switcho.it\/servizi\/intro\/luce-gas\"><strong>noi di Switcho<\/strong><\/a> a individuare le <a href=\"https:\/\/www.switcho.it\/risorse\/luce-gas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>offerte luce e gas<\/strong><\/a><strong> pi\u00f9 convenienti<\/strong>. Ci occupiamo anche della burocrazia legata al cambio fornitore. Il nostro servizio \u00e8 <strong>100% digitale e gratuito<\/strong>.\u00a0<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.19.1&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.19.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-low-desktop.png&#8221; alt=&#8221;risparmia sulle bollette con switcho&#8221; title_text=&#8221;risparmia sulle bollette con switcho&#8221; url=&#8221;http:\/\/www.switcho.it\/servizi\/intro\/luce-gas?ref=cta-energy-low&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; src_tablet=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-low-mobile.png&#8221; src_phone=&#8221;https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2022\/11\/banner-energy-low-mobile.png&#8221; src_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_toggle title=&#8221;Fonti&#8221; open_toggle_background_color=&#8221;#F7F8FA&#8221; closed_toggle_text_color=&#8221;#2D3748&#8243; closed_toggle_background_color=&#8221;#f7f8fa&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;||||||||&#8221; title_font_size=&#8221;18px&#8221; title_line_height=&#8221;1.7em&#8221; closed_title_font=&#8221;||||||||&#8221; closed_title_font_size=&#8221;18px&#8221; body_font=&#8221;||||||||&#8221; hover_enabled=&#8221;0&#8243; body_font_size_tablet=&#8221;16px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<span>Contatti | Octopus Energy<\/span>\n<br><span><a href=\"https:\/\/octopusenergy.it\/contatti\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/octopusenergy.it\/contatti<\/a><\/span>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.<\/p>\n","protected":false},"author":40,"featured_media":152267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[313],"tags":[],"class_list":["post-152273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contatti-fornitori-energia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Numero Verde Octopus Energy: tutti i Contatti del Fornitore - Switcho<\/title>\n<meta name=\"description\" content=\"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Numero Verde Octopus Energy: tutti i Contatti del Fornitore\" \/>\n<meta property=\"og:description\" content=\"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/\" \/>\n<meta property=\"og:site_name\" content=\"Switcho\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-20T11:48:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T11:48:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federica Antignano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Numero Verde Octopus Energy: tutti i Contatti del Fornitore\" \/>\n<meta name=\"twitter:description\" content=\"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica Antignano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/\"},\"author\":{\"name\":\"Federica Antignano\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/person\\\/f45c81c5f7aac87dbb9cf5455d33e0c6\"},\"headline\":\"Numero verde Octopus e contatti del servizio clienti\",\"datePublished\":\"2026-02-20T11:48:09+00:00\",\"dateModified\":\"2026-02-20T11:48:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/\"},\"wordCount\":988,\"publisher\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Contatti-Octopus-Energy.png\",\"articleSection\":[\"Contatti Fornitori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/\",\"name\":\"Numero Verde Octopus Energy: tutti i Contatti del Fornitore - Switcho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Contatti-Octopus-Energy.png\",\"datePublished\":\"2026-02-20T11:48:09+00:00\",\"dateModified\":\"2026-02-20T11:48:10+00:00\",\"description\":\"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Contatti-Octopus-Energy.png\",\"contentUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Contatti-Octopus-Energy.png\",\"width\":1200,\"height\":800,\"caption\":\"numero verde contatti octopus energy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/numero-verde-contatti-octopus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luce e Gas\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Contatti Fornitori\",\"item\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/luce-gas\\\/contatti-fornitori-energia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Numero verde Octopus e contatti del servizio clienti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\",\"name\":\"Switcho\",\"description\":\"Il blog semplice, per davvero.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#organization\",\"name\":\"Switcho\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Switcho-Logotype-Green.png\",\"contentUrl\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Switcho-Logotype-Green.png\",\"width\":1507,\"height\":597,\"caption\":\"Switcho\"},\"image\":{\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/#\\\/schema\\\/person\\\/f45c81c5f7aac87dbb9cf5455d33e0c6\",\"name\":\"Federica Antignano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g\",\"caption\":\"Federica Antignano\"},\"description\":\"Web writer e copywriter con esperienza nella redazione di contenuti in ambito energia e finanza per importanti testate online, Federica affianca il team Switcho come collaboratrice esterna nella creazione di articoli per il blog aziendale. La sua dedizione va oltre il semplice lavoro, \u00e8 un impegno sincero nel fornire informazioni utili e contenuti di valore ai lettori.\",\"url\":\"https:\\\/\\\/www.switcho.it\\\/blog\\\/author\\\/federica-antignano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Numero Verde Octopus Energy: tutti i Contatti del Fornitore - Switcho","description":"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/","og_locale":"it_IT","og_type":"article","og_title":"Numero Verde Octopus Energy: tutti i Contatti del Fornitore","og_description":"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.","og_url":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/","og_site_name":"Switcho","article_published_time":"2026-02-20T11:48:09+00:00","article_modified_time":"2026-02-20T11:48:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","type":"image\/png"}],"author":"Federica Antignano","twitter_card":"summary_large_image","twitter_title":"Numero Verde Octopus Energy: tutti i Contatti del Fornitore","twitter_description":"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.","twitter_image":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","twitter_misc":{"Scritto da":"Federica Antignano","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#article","isPartOf":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/"},"author":{"name":"Federica Antignano","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/person\/f45c81c5f7aac87dbb9cf5455d33e0c6"},"headline":"Numero verde Octopus e contatti del servizio clienti","datePublished":"2026-02-20T11:48:09+00:00","dateModified":"2026-02-20T11:48:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/"},"wordCount":988,"publisher":{"@id":"https:\/\/www.switcho.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","articleSection":["Contatti Fornitori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/","url":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/","name":"Numero Verde Octopus Energy: tutti i Contatti del Fornitore - Switcho","isPartOf":{"@id":"https:\/\/www.switcho.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#primaryimage"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","datePublished":"2026-02-20T11:48:09+00:00","dateModified":"2026-02-20T11:48:10+00:00","description":"Scopri il numero Octopus, indirizzo email e gli altri contatti online per richiedere assistenza e inviare reclami.","breadcrumb":{"@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#primaryimage","url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","contentUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2026\/02\/Contatti-Octopus-Energy.png","width":1200,"height":800,"caption":"numero verde contatti octopus energy"},{"@type":"BreadcrumbList","@id":"https:\/\/www.switcho.it\/blog\/luce-gas\/numero-verde-contatti-octopus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.switcho.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Luce e Gas","item":"https:\/\/www.switcho.it\/blog\/luce-gas\/"},{"@type":"ListItem","position":3,"name":"Contatti Fornitori","item":"https:\/\/www.switcho.it\/blog\/luce-gas\/contatti-fornitori-energia\/"},{"@type":"ListItem","position":4,"name":"Numero verde Octopus e contatti del servizio clienti"}]},{"@type":"WebSite","@id":"https:\/\/www.switcho.it\/blog\/#website","url":"https:\/\/www.switcho.it\/blog\/","name":"Switcho","description":"Il blog semplice, per davvero.","publisher":{"@id":"https:\/\/www.switcho.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.switcho.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.switcho.it\/blog\/#organization","name":"Switcho","url":"https:\/\/www.switcho.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2021\/03\/Switcho-Logotype-Green.png","contentUrl":"https:\/\/www.switcho.it\/blog\/wp-content\/uploads\/2021\/03\/Switcho-Logotype-Green.png","width":1507,"height":597,"caption":"Switcho"},"image":{"@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.switcho.it\/blog\/#\/schema\/person\/f45c81c5f7aac87dbb9cf5455d33e0c6","name":"Federica Antignano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca51910f09bc09090018066fe53b8f96f6f12e754c122d3dcb383514cfb9cea?s=96&d=mm&r=g","caption":"Federica Antignano"},"description":"Web writer e copywriter con esperienza nella redazione di contenuti in ambito energia e finanza per importanti testate online, Federica affianca il team Switcho come collaboratrice esterna nella creazione di articoli per il blog aziendale. La sua dedizione va oltre il semplice lavoro, \u00e8 un impegno sincero nel fornire informazioni utili e contenuti di valore ai lettori.","url":"https:\/\/www.switcho.it\/blog\/author\/federica-antignano\/"}]}},"modified_by":"Raffaella Di Marco","_links":{"self":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/152273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/comments?post=152273"}],"version-history":[{"count":4,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/152273\/revisions"}],"predecessor-version":[{"id":152312,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/posts\/152273\/revisions\/152312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/media\/152267"}],"wp:attachment":[{"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/media?parent=152273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/categories?post=152273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.switcho.it\/blog\/wp-json\/wp\/v2\/tags?post=152273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}